{"id":1508,"date":"2013-07-17T17:39:04","date_gmt":"2013-07-17T15:39:04","guid":{"rendered":"http:\/\/www.la-boite-a-finances.com\/blog\/?p=1508"},"modified":"2020-03-04T22:16:58","modified_gmt":"2020-03-04T20:16:58","slug":"taxe-tobin-le-plus-populaire-des-impots","status":"publish","type":"post","link":"https:\/\/la-boite-a-finances.com\/blog\/taxe-tobin-le-plus-populaire-des-impots\/","title":{"rendered":"Taxe Tobin\u00a0: le plus populaire des imp\u00f4ts"},"content":{"rendered":"<p>J&rsquo;ai l&rsquo;impression que cette id\u00e9e de taxer les transactions financi\u00e8res est plus populiste qu&rsquo;autre chose.<br \/>\nElle devient le symbole de la lutte contre le monde de la finance et de l&rsquo;argent facile\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<p>Elle ne fera que mettre au ch\u00f4mage quelques informaticiens, math\u00e9maticiens et fournisseurs de r\u00e9seaux ultra haut d\u00e9bit.<br \/>\nDans le fond, le march\u00e9 n&rsquo;en a que faire de la vitesse et de la fr\u00e9quence des \u00ab\u00a0trades\u00a0\u00bb. Si cette taxe devait voir le jour, les investisseurs se contenteront d&rsquo;investir sur des dur\u00e9es plus en rapport avec les capacit\u00e9s cognitives du cerveau humain.<br \/>\nLe march\u00e9 existe selon les conditions qu&rsquo;il rencontre.<br \/>\nC&rsquo;est un concept et non une personne dot\u00e9e d&rsquo;une capacit\u00e9 \u00e9thique ou d&rsquo;une conviction politique<br \/>\n\u2026 \u00e0 l&rsquo;oppos\u00e9 de l&rsquo;investisseur.<\/p>\n<p>Par contre, le risque est de freiner les arbitrages et de \u00ab\u00a0viscoser\u00a0\u00bb <strong>le march\u00e9 qui deviendrait beaucoup moins \u00ab\u00a0liquide\u00a0\u00bb<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p>Le risque de cette taxe serait de <strong>rendre le march\u00e9 moins efficace et donc d&rsquo;en limiter l&rsquo;\u00e9quit\u00e9<\/strong>\u00a0: l&rsquo;argent rejoignant moins facilement les projets risqu\u00e9s, ambitieux, originaux et ceux qu&rsquo;affectionnent les investisseurs, donc les citoyens (l&rsquo;investissement du particulier, c&rsquo;est avant tout une fa\u00e7on de d\u00e9cider de l&rsquo;avenir du monde\u2026 \u00e0 la mesure de ses moyens).<\/p>\n<p>Quand je vous dirais : on peut investir sur ce truc nouveau qui va faire progresser la soci\u00e9t\u00e9, sauver la couche d&rsquo;ozone, les baleines, combattre la mal-nutrition et le cancer. Cependant, c&rsquo;est risqu\u00e9 et si \u00e7a ne marche pas vous aurez plus de mal qu\u00a0\u00bbavant la mise en place de la taxe Tobin, \u00e0 retirer votre argent.<br \/>\nQue me r\u00e9pondrez-vous\u00a0?<br \/>\nJe veux bien investir, mais moins que je ne l&rsquo;aurais fait avant l\u2019av\u00e8nement de cette taxe ?<\/p>\n<p>Je viens de me contenter du terme \u00ab\u00a0\u00e9quit\u00e9\u00a0\u00bb \u00e0 la place de \u00ab\u00a0juste\u00a0\u00bb.<br \/>\nEn effet, je ne me sens pas l\u00e9gitime pour dire s&rsquo;il est juste que ce soit les investisseurs qui d\u00e9cident qui doit profiter des moyens (financiers, mat\u00e9riels, humains\u2026) et qui doit p\u00e2tir de leur absence.<br \/>\nOn a plus ou moins essay\u00e9 de donner le m\u00eame pouvoir de d\u00e9cision \u00e0 chaque \u00eatre humain par l&rsquo;interm\u00e9diaire du droit de vote unique par citoyen et de la d\u00e9mocratie.<br \/>\nCela me semble \u00ab\u00a0juste\u00a0\u00bb.<br \/>\nLe fait de donner les m\u00eames chances aux investisseurs me semble plut\u00f4t \u00ab\u00a0\u00e9quitable\u00a0\u00bb.<br \/>\nLes citoyens naissent \u00ab\u00a0libres et \u00e9gaux\u00a0\u00bb, mais par l&rsquo;exercice de leur libert\u00e9, ils n&rsquo;ont pas tous les m\u00eame moyens financiers.<\/p>\n<p>Revenons \u00e0 cette taxe et posons-nous la principale question\u00a0: <strong>serait-elle l\u00e9gitime\u00a0?<\/strong><\/p>\n<p>\u00c0 mon sens, elle est moins l\u00e9gitime qu&rsquo;un imp\u00f4t sur le revenu, sur la fortune, ou sur les successions.<br \/>\nEn effet, <strong>elle se dresse contre<\/strong> un principe qui a permis la forme de progr\u00e8s que l&rsquo;on conna\u00eet\u00a0: <strong>la loi du march\u00e9<\/strong>.<br \/>\nElle <strong>ne se dresse pas<\/strong> contre l&rsquo;augmentation des <strong>\u00e9carts sociaux<\/strong>.<br \/>\nAinsi, elle est aussi peu l\u00e9gitime que la TVA et produirait des effets comparables\u00a0: freiner le commerce et d\u00e9velopper des \u00e9conomies parall\u00e8les.<\/p>\n<p>Avec la taxe Tobin, on verrait les investissements frein\u00e9s dans leurs \u00e9lans et le d\u00e9veloppement de march\u00e9s financiers occultes comme ceux des pays qui ne l&rsquo;appliqueraient pas (paradis fiscaux, par exemple), mais aussi des march\u00e9s entre les institutions financi\u00e8res qui s&rsquo;\u00e9changeraient (ou se pr\u00eateraient) des titres sans en r\u00e9f\u00e9rer aux autorit\u00e9s.<br \/>\nJe devrais m\u00eame \u00e9crire \u00ab\u00a0qui s&rsquo;\u00e9changent d\u00e9j\u00e0 des titres\u00bb, puisque c&rsquo;est le cas&#8230;<\/p>\n<p>En conclusion, si nos dirigeants politiques veulent lever plus d&rsquo;imp\u00f4ts, je leur propose d&rsquo;augmenter les taxes existantes et surtout de s&rsquo;entendre entre les pays pour emp\u00eacher (au moins limiter) l&rsquo;\u00e9vasion fiscale et autre forme d&rsquo;optimisation qui ne profitent qu&rsquo;\u00e0 certains.<br \/>\nPersonnellement, je ne suis pas contre payer des imp\u00f4ts, j&rsquo;ai juste envie de ne pas en payer plus que mon voisin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai l&rsquo;impression que cette id\u00e9e de taxer les transactions financi\u00e8res est plus populiste qu&rsquo;autre chose. Elle devient le symbole de<a href=\"https:\/\/la-boite-a-finances.com\/blog\/taxe-tobin-le-plus-populaire-des-impots\/\" class=\"searchmore\"> Lire la suite&#8230;<\/a><\/p>\n<div class=\"clr\"><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[466,465,467],"class_list":["post-1508","post","type-post","status-publish","format-standard","hentry","category-marches-financiers","tag-impot-transactions-financieres","tag-taxe-financiere","tag-taxe-tobin"],"_links":{"self":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/posts\/1508"}],"collection":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/comments?post=1508"}],"version-history":[{"count":0,"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/posts\/1508\/revisions"}],"wp:attachment":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/media?parent=1508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/categories?post=1508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/tags?post=1508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}