{"id":97,"count":3,"description":"","link":"https:\/\/la-boite-a-finances.com\/blog\/tag\/livret-a\/","name":"livret A","slug":"livret-a","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/tags\/97"}],"collection":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/la-boite-a-finances.com\/blog\/wp-json\/wp\/v2\/posts?tags=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}